{"id":22,"count":1,"description":"","link":"https:\/\/lagravera.com\/en\/category\/experiences\/","name":"Experiences","slug":"experiences","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Experiences archivos - Lagravera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lagravera.com\/en\/category\/experiences\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Experiences archivos - Lagravera\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lagravera.com\/en\/category\/experiences\/\" \/>\n<meta property=\"og:site_name\" content=\"Lagravera\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/lagravera.com\\\/en\\\/category\\\/experiences\\\/\",\"url\":\"https:\\\/\\\/lagravera.com\\\/en\\\/category\\\/experiences\\\/\",\"name\":\"Experiences archivos - Lagravera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lagravera.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lagravera.com\\\/en\\\/category\\\/experiences\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lagravera.com\\\/en\\\/category\\\/experiences\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lagravera.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Experiences\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lagravera.com\\\/#website\",\"url\":\"https:\\\/\\\/lagravera.com\\\/\",\"name\":\"Lagravera\",\"description\":\"Diferentes por naturaleza\",\"publisher\":{\"@id\":\"https:\\\/\\\/lagravera.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lagravera.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lagravera.com\\\/#organization\",\"name\":\"Lagravera\",\"url\":\"https:\\\/\\\/lagravera.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lagravera.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lagravera.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/lagravera.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/favicon.png\",\"width\":600,\"height\":600,\"caption\":\"Lagravera\"},\"image\":{\"@id\":\"https:\\\/\\\/lagravera.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bodega.lagravera\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/celler-lagravera-sl\\\/\",\"https:\\\/\\\/www.instagram.com\\\/lagravera\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Experiences archivos - Lagravera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lagravera.com\/en\/category\/experiences\/","og_locale":"en_US","og_type":"article","og_title":"Experiences archivos - Lagravera","og_url":"https:\/\/lagravera.com\/en\/category\/experiences\/","og_site_name":"Lagravera","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lagravera.com\/en\/category\/experiences\/","url":"https:\/\/lagravera.com\/en\/category\/experiences\/","name":"Experiences archivos - Lagravera","isPartOf":{"@id":"https:\/\/lagravera.com\/#website"},"breadcrumb":{"@id":"https:\/\/lagravera.com\/en\/category\/experiences\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/lagravera.com\/en\/category\/experiences\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lagravera.com\/en\/"},{"@type":"ListItem","position":2,"name":"Experiences"}]},{"@type":"WebSite","@id":"https:\/\/lagravera.com\/#website","url":"https:\/\/lagravera.com\/","name":"Lagravera","description":"Diferentes por naturaleza","publisher":{"@id":"https:\/\/lagravera.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lagravera.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lagravera.com\/#organization","name":"Lagravera","url":"https:\/\/lagravera.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lagravera.com\/#\/schema\/logo\/image\/","url":"https:\/\/lagravera.com\/wp-content\/uploads\/2022\/07\/favicon.png","contentUrl":"https:\/\/lagravera.com\/wp-content\/uploads\/2022\/07\/favicon.png","width":600,"height":600,"caption":"Lagravera"},"image":{"@id":"https:\/\/lagravera.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bodega.lagravera","https:\/\/www.linkedin.com\/company\/celler-lagravera-sl\/","https:\/\/www.instagram.com\/lagravera\/"]}]}},"_links":{"self":[{"href":"https:\/\/lagravera.com\/en\/wp-json\/wp\/v2\/categories\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagravera.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/lagravera.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/lagravera.com\/en\/wp-json\/wp\/v2\/posts?categories=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}